{"id":3788,"date":"2019-03-26T18:46:17","date_gmt":"2019-03-26T18:46:17","guid":{"rendered":"https:\/\/www.48hopenhousebarcelona.org\/obrim-la-convocatoria-a-nous-edificis-per-lohb19-2\/"},"modified":"2019-09-22T18:50:21","modified_gmt":"2019-09-22T18:50:21","slug":"obrim-la-convocatoria-a-nous-edificis-per-lohb19-2","status":"publish","type":"post","link":"https:\/\/www.48hopenhousebarcelona.org\/es\/obrim-la-convocatoria-a-nous-edificis-per-lohb19-2\/","title":{"rendered":"\u00a1Abrimos la convocatoria a nuevos edificios para el OHB19!"},"content":{"rendered":"<p>Se abre el plazo de inscripci\u00f3n para edificios de<strong>\u00a0<\/strong>la d\u00e9cima edici\u00f3n del festival. Estamos buscando nuevos edificios, reformas o espacios p\u00fablicos de Barcelona que quieran participar al OHB19.<\/p>\n<p>El 48h\u00a0Open\u00a0House\u00a0Bcn\u00a0es un evento cultural anual de divulgaci\u00f3n de la arquitectura, el urbanismo y el dise\u00f1o, y\u00a0este 2019 tendr\u00e1 lugar durante el fin de semana 26 y 27 de octubre, siendo esta la celebraci\u00f3n de la 10\u00aa edici\u00f3n del Festival! Ya hace diez a\u00f1os que el 48HOHB forma parte de la red internacional\u00a0Open\u00a0House\u00a0World\u00a0Wide, en que tienen cabida 41 ciudades en m\u00e1s de los 5 continentes.<\/p>\n<p><strong>Quer\u00e9is proponer alg\u00fan edificio? Adelante!<\/strong><br \/>\n<a class=\"action\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSe1UgfQ-cXr3CuBEL1fIrmItRJjcleHWJntbmMhp_035tcOpw\/viewform\" target=\"_blank\" rel=\"noopener noreferrer\">FORMULARIO DE INSCRIPCI\u00d3N<\/a><\/p>\n<p>El 48h\u00a0Open\u00a0House\u00a0Bcn\u00a0se hace cargo de la organizaci\u00f3n de las visitas, de la formaci\u00f3n y asignaci\u00f3n de voluntarios, de la coordinaci\u00f3n con la propiedad y\/o gestor, aportando los informadores necesarios para la gesti\u00f3n de los grupos y las visitas. Aun as\u00ed el 48h\u00a0Open\u00a0House Bcn, se responsabilizar\u00e1 de la campa\u00f1a de comunicaci\u00f3n a trav\u00e9s de todos los canales de comunicaci\u00f3n de la Asociaci\u00f3n y de la asignaci\u00f3n de un interlocutor para cada edificio como responsable de zona.\u00a0<em>(Los edificios participantes en el Festival, tienen que tener un seguro de responsabilidad civil, al margen de la global que dispone el Festival)<\/em><\/p>\n<p>Si est\u00e1is interesados a compartir alg\u00fan espacio que gestion\u00e1is, ense\u00f1ar alguno\u00a0de vuestros proyectos\u00a0o hacernos alguna propuesta, pod\u00e9is rellenar el formulario de inscripci\u00f3n:<\/p>\n<p>\u00a1MUCHAS GRACIAS!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se abre el plazo de inscripci\u00f3n para edificios de la d\u00e9cima<\/p>\n","protected":false},"author":2,"featured_media":3784,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.48hopenhousebarcelona.org\/es\/wp-json\/wp\/v2\/posts\/3788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.48hopenhousebarcelona.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.48hopenhousebarcelona.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.48hopenhousebarcelona.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.48hopenhousebarcelona.org\/es\/wp-json\/wp\/v2\/comments?post=3788"}],"version-history":[{"count":2,"href":"https:\/\/www.48hopenhousebarcelona.org\/es\/wp-json\/wp\/v2\/posts\/3788\/revisions"}],"predecessor-version":[{"id":3790,"href":"https:\/\/www.48hopenhousebarcelona.org\/es\/wp-json\/wp\/v2\/posts\/3788\/revisions\/3790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.48hopenhousebarcelona.org\/es\/wp-json\/wp\/v2\/media\/3784"}],"wp:attachment":[{"href":"https:\/\/www.48hopenhousebarcelona.org\/es\/wp-json\/wp\/v2\/media?parent=3788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.48hopenhousebarcelona.org\/es\/wp-json\/wp\/v2\/categories?post=3788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.48hopenhousebarcelona.org\/es\/wp-json\/wp\/v2\/tags?post=3788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}